{"id":1431,"date":"2018-07-17T12:09:14","date_gmt":"2018-07-17T15:09:14","guid":{"rendered":"http:\/\/elosit.com.br\/equipamento-portatil-xxxxxxxx\/"},"modified":"2018-07-17T12:09:14","modified_gmt":"2018-07-17T15:09:14","slug":"equipamento-portatil-xxxxxxxx","status":"publish","type":"post","link":"http:\/\/elosit.com.br\/en\/equipamento-portatil-xxxxxxxx\/","title":{"rendered":"Equipamento port\u00e1til XXXXXXXX"},"content":{"rendered":"<p><span style=\"color: #0b436d;\"><strong>XXXXXXX<\/strong> <\/span>Delega\u00e7\u00e3o brasileira participante do F\u00f3rum Mundial da \u00c1gua 2015, realizado na Coreia do Sul<\/p>\n<p><span style=\"color: #0b436d;\"><strong>O problema:<\/strong><\/span> Log\u00edstica de equipamento port\u00e1til de interpreta\u00e7\u00e3o no interior da Coreia do Sul<\/p>\n<p><span style=\"color: #0b436d;\"><strong>O caso:<\/strong><\/span> A contrata\u00e7\u00e3o do servi\u00e7o de interpreta\u00e7\u00e3o para a delega\u00e7\u00e3o previa o uso do kit de equipamento port\u00e1til, e os locais do evento \u2013 Daegu e Gyeongbuk, no interior do pa\u00eds \u2013 constitu\u00edam um desafio adicional. A op\u00e7\u00e3o inicial de levar os equipamentos do Brasil foi descartada. Al\u00e9m da poss\u00edvel dificuldade de passagem dos equipamentos pela aduana sulcoreana, o tempo de trajeto BrasilCoreiaBrasil representaria um acr\u00e9scimo de custo, visto que a base de c\u00e1lculo da loca\u00e7\u00e3o \u00e9 di\u00e1ria. A contrata\u00e7\u00e3o do equipamento em Seul era igualmente invi\u00e1vel, j\u00e1 que o aeroporto de chegada era afastado da cidade e j\u00e1 estava previsto o deslocamento de trem para os locais do evento logo \u00e0 chegada. Diante do impasse, Marsel entrou em contato com colegas sulcoreanos da Associa\u00e7\u00e3o Internacional dos Int\u00e9rpretes de Confer\u00eancia (AIIC) para pedir orienta\u00e7\u00e3o.<\/p>\n<p><span style=\"color: #0b436d;\"><strong>A solu\u00e7\u00e3o:<\/strong><\/span> Um dos colegas de associa\u00e7\u00e3o sulcoreanos que trabalharia no mesmo evento colocou Marsel em contato com a empresa encarregada de fornecer toda a aparelhagem do F\u00f3rum, que muito prontamente negociou a entrega do kit no pr\u00f3prio local do evento.<\/p>\n<p><span style=\"color: #0b436d;\"><strong>O resultado:<\/strong><\/span> A solu\u00e7\u00e3o poupou malabarismos log\u00edsticos e custos, al\u00e9m de assegurar a correta din\u00e2mica da comunica\u00e7\u00e3o da delega\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>XXXXXXX Delega\u00e7\u00e3o brasileira participante do F\u00f3rum Mundial da \u00c1gua 2015,  [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-1431","post","type-post","status-publish","format-standard","hentry","category-casos-en"],"_links":{"self":[{"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/posts\/1431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/comments?post=1431"}],"version-history":[{"count":0,"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/posts\/1431\/revisions"}],"wp:attachment":[{"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/media?parent=1431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/categories?post=1431"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/elosit.com.br\/en\/wp-json\/wp\/v2\/tags?post=1431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}